{"id":3308,"date":"2018-10-20T11:44:21","date_gmt":"2018-10-20T11:44:21","guid":{"rendered":"http:\/\/omnimissions.com\/site\/?p=3308"},"modified":"2018-10-28T12:10:25","modified_gmt":"2018-10-28T12:10:25","slug":"nsobe-game-camp","status":"publish","type":"post","link":"https:\/\/omnimissions.com\/site\/nsobe-game-camp\/","title":{"rendered":"Nsobe Game Camp"},"content":{"rendered":"<p>Students from the OMNI School take an educational tour of the Nsobe Animal Park.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3309\" src=\"http:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_093834-1024x768.jpg\" alt=\"\" width=\"970\" height=\"728\" srcset=\"https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_093834-1024x768.jpg 1024w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_093834-300x225.jpg 300w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_093834-768x576.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3310\" src=\"http:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113407-1024x768.jpg\" alt=\"\" width=\"970\" height=\"728\" srcset=\"https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113407-1024x768.jpg 1024w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113407-300x225.jpg 300w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113407-768x576.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/> <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3311\" src=\"http:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113438-1024x768.jpg\" alt=\"\" width=\"970\" height=\"728\" srcset=\"https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113438-1024x768.jpg 1024w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113438-300x225.jpg 300w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_113438-768x576.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/> <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3312\" src=\"http:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_131928-1024x768.jpg\" alt=\"\" width=\"970\" height=\"728\" srcset=\"https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_131928-1024x768.jpg 1024w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_131928-300x225.jpg 300w, https:\/\/omnimissions.com\/site\/wp-content\/uploads\/2018\/10\/IMG_20181012_131928-768x576.jpg 768w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Students from the OMNI School take an educational tour of the Nsobe Animal Park.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3308","post","type-post","status-publish","format-standard","hentry","category-omni"],"_links":{"self":[{"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/posts\/3308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/comments?post=3308"}],"version-history":[{"count":1,"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/posts\/3308\/revisions"}],"predecessor-version":[{"id":3313,"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/posts\/3308\/revisions\/3313"}],"wp:attachment":[{"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/media?parent=3308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/categories?post=3308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/omnimissions.com\/site\/wp-json\/wp\/v2\/tags?post=3308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}